{"id":1428,"date":"2014-11-24T18:39:13","date_gmt":"2014-11-24T18:39:13","guid":{"rendered":"https:\/\/cherscholar.com\/cherblog\/sonny-cher-frieda-dh\/"},"modified":"2023-02-20T08:21:03","modified_gmt":"2023-02-20T15:21:03","slug":"sonny-cher-frieda-dh","status":"publish","type":"post","link":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/","title":{"rendered":"Sonny &#038; Cher &#038; Frieda &#038; D.H."},"content":{"rendered":"<p>For my novel I\u2019ve been researching New Mexico history, artists and writers. You keep coming across D.H. Lawrence (who wrote <em>Lady Chatterly\u2019s Lover<\/em> in 1928) as an icon of Taos, New Mexico &#8212; this even though he only lived in Taos a brief time and made disparaging comments about his time there.<\/p>\n<p>In any case, this below is a picture of D. H. Lawrence and his wife, Frieda, (who did go back to Taos after her husband\u2019s death), and was taken in Mexico. It&#39;s a very famous and often used photo of D. H. Lawrence.<\/p>\n<p>This is all to say this famous picture reminds me of another, quite obscure, Sonny &amp; Cher photo below which was part of a Billboard ad for &quot;The Beat Goes On.&quot;<\/p>\n<p><a class=\"asset-img-link\" href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef01b7c70f1fc9970b-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"float: left;\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"Friedadh\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef01b7c70f1fc9970b img-responsive\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg?w=676&#038;ssl=1\" style=\"width: 194px; margin: 0px 5px 5px 0px;\" title=\"Friedadh\" \/><\/a> &#0160; <a class=\"asset-img-link\" href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef01b7c70f211c970b-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"float: left;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" alt=\"What the\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef01b7c70f211c970b img-responsive\" height=\"260\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef01b7c70f211c970b-200wi.jpg?resize=223%2C260&#038;ssl=1\" style=\"width: 200px; margin: 0px 5px 5px 0px;\" title=\"What the\" width=\"223\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>For my novel I\u2019ve been researching New Mexico history, artists and writers. You keep coming across D.H. Lawrence (who wrote Lady Chatterly\u2019s Lover in 1928) as an icon of Taos, New Mexico &#8212; this even though he only lived in Taos a brief time and made disparaging comments about his time there. In any case, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[102],"tags":[],"class_list":["post-1428","post","type-post","status-publish","format-standard","hentry","category-cher-in-art-literature","wp-image-borders","post-preview"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sonny &amp; Cher &amp; Frieda &amp; D.H. - I Found Some Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sonny &amp; Cher &amp; Frieda &amp; D.H. - I Found Some Blog\" \/>\n<meta property=\"og:description\" content=\"For my novel I\u2019ve been researching New Mexico history, artists and writers. You keep coming across D.H. Lawrence (who wrote Lady Chatterly\u2019s Lover in 1928) as an icon of Taos, New Mexico &#8212; this even though he only lived in Taos a brief time and made disparaging comments about his time there. In any case, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/\" \/>\n<meta property=\"og:site_name\" content=\"I Found Some Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/twitter.com\/Mary_McCray\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-24T18:39:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T15:21:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg\" \/>\n<meta name=\"author\" content=\"Cher Scholar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Mary_McCray\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cher Scholar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/\"},\"author\":{\"name\":\"Cher Scholar\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/1486194d52b3026c77cf22dd16c4cb3c\"},\"headline\":\"Sonny &#038; Cher &#038; Frieda &#038; D.H.\",\"datePublished\":\"2014-11-24T18:39:13+00:00\",\"dateModified\":\"2023-02-20T15:21:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/\"},\"wordCount\":137,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\"},\"image\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg\",\"articleSection\":[\"Cher in Art &amp; Literature\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/\",\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/\",\"name\":\"Sonny & Cher & Frieda & D.H. - I Found Some Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg\",\"datePublished\":\"2014-11-24T18:39:13+00:00\",\"dateModified\":\"2023-02-20T15:21:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg?fit=194%2C259&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg?fit=194%2C259&ssl=1\",\"width\":194,\"height\":259},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2014\\\/11\\\/sonny-cher-frieda-dh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sonny &#038; Cher &#038; Frieda &#038; D.H.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#website\",\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/\",\"name\":\"I Found Some Blog\",\"description\":\"a division of the Chersonian Institute\",\"publisher\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\",\"name\":\"Cher Scholar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"caption\":\"Cher Scholar\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/Mary_McCray\",\"https:\\\/\\\/www.pinterest.com\\\/poetmarymccray\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Mary_McCray\",\"https:\\\/\\\/marymccray.tumblr.com\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/1486194d52b3026c77cf22dd16c4cb3c\",\"name\":\"Cher Scholar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"caption\":\"Cher Scholar\"},\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/author\\\/cherscholar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sonny & Cher & Frieda & D.H. - I Found Some Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/","og_locale":"en_US","og_type":"article","og_title":"Sonny & Cher & Frieda & D.H. - I Found Some Blog","og_description":"For my novel I\u2019ve been researching New Mexico history, artists and writers. You keep coming across D.H. Lawrence (who wrote Lady Chatterly\u2019s Lover in 1928) as an icon of Taos, New Mexico &#8212; this even though he only lived in Taos a brief time and made disparaging comments about his time there. In any case, [&hellip;]","og_url":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/","og_site_name":"I Found Some Blog","article_publisher":"https:\/\/twitter.com\/Mary_McCray","article_published_time":"2014-11-24T18:39:13+00:00","article_modified_time":"2023-02-20T15:21:03+00:00","og_image":[{"url":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg","type":"","width":"","height":""}],"author":"Cher Scholar","twitter_card":"summary_large_image","twitter_site":"@Mary_McCray","twitter_misc":{"Written by":"Cher Scholar","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/#article","isPartOf":{"@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/"},"author":{"name":"Cher Scholar","@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/1486194d52b3026c77cf22dd16c4cb3c"},"headline":"Sonny &#038; Cher &#038; Frieda &#038; D.H.","datePublished":"2014-11-24T18:39:13+00:00","dateModified":"2023-02-20T15:21:03+00:00","mainEntityOfPage":{"@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/"},"wordCount":137,"commentCount":0,"publisher":{"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1"},"image":{"@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/#primaryimage"},"thumbnailUrl":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg","articleSection":["Cher in Art &amp; Literature"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/","url":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/","name":"Sonny & Cher & Frieda & D.H. - I Found Some Blog","isPartOf":{"@id":"https:\/\/cherscholar.com\/cherblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/#primaryimage"},"image":{"@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/#primaryimage"},"thumbnailUrl":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg","datePublished":"2014-11-24T18:39:13+00:00","dateModified":"2023-02-20T15:21:03+00:00","breadcrumb":{"@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/#primaryimage","url":"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg?fit=194%2C259&ssl=1","contentUrl":"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef01b7c70f1fc9970b-200wi.jpg?fit=194%2C259&ssl=1","width":194,"height":259},{"@type":"BreadcrumbList","@id":"https:\/\/cherscholar.com\/cherblog\/2014\/11\/sonny-cher-frieda-dh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cherscholar.com\/cherblog\/"},{"@type":"ListItem","position":2,"name":"Sonny &#038; Cher &#038; Frieda &#038; D.H."}]},{"@type":"WebSite","@id":"https:\/\/cherscholar.com\/cherblog\/#website","url":"https:\/\/cherscholar.com\/cherblog\/","name":"I Found Some Blog","description":"a division of the Chersonian Institute","publisher":{"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cherscholar.com\/cherblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1","name":"Cher Scholar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","caption":"Cher Scholar"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g"},"sameAs":["https:\/\/twitter.com\/Mary_McCray","https:\/\/www.pinterest.com\/poetmarymccray\/","https:\/\/x.com\/https:\/\/twitter.com\/Mary_McCray","https:\/\/marymccray.tumblr.com\/"]},{"@type":"Person","@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/1486194d52b3026c77cf22dd16c4cb3c","name":"Cher Scholar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","caption":"Cher Scholar"},"url":"https:\/\/cherscholar.com\/cherblog\/author\/cherscholar\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/1428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/comments?post=1428"}],"version-history":[{"count":1,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/1428\/revisions"}],"predecessor-version":[{"id":4853,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/1428\/revisions\/4853"}],"wp:attachment":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/media?parent=1428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/categories?post=1428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/tags?post=1428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}