{"id":2135,"date":"2012-11-18T11:45:06","date_gmt":"2012-11-18T11:45:06","guid":{"rendered":"https:\/\/cherscholar.com\/cherblog\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/"},"modified":"2023-02-20T08:27:38","modified_gmt":"2023-02-20T15:27:38","slug":"go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best","status":"publish","type":"post","link":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/","title":{"rendered":"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best?"},"content":{"rendered":"<p>\n<a class=\"asset-img-link\" href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef017c33b32e02970b-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"float: left;\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"Bodysuit\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef017c33b32e02970b\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg?w=676&#038;ssl=1\" style=\"width: 200px; margin: 0px 5px 5px 0px;\" title=\"Bodysuit\" \/><\/a>People Magazine is running a bodysuit poll and who doesn&#39;t care about bodysuits so go make your voice heard:<\/p>\n<p style=\"padding-left: 30px;\"><em>Banging bodies. Major success. Sheer jumpsuits. Three things Kristen Stewart and Cher have in common. But does K. Stew\u2019s Zuhair Murad creation live up to Cher\u2019s legendary black bodysuit?<\/em><\/p>\n<p><em>Stewart wore her revealing ensemble \u2014 a shimmering, backless number \u2014 to the London premiere of The Twilight Saga: Breaking Dawn \u2014 Part 2 on Wednesday and earned mixed reviews from readers, some of whom found it sexy and some who thought it was salacious.<\/em><\/p>\n<p><em>Cher has worn black bodysuits a zillion times throughout her career, most recently to the 2010 MTV Video Music Awards (left) \u2014 and most famously in her \u201cIf I Could Turn Back Time\u201d video. And we\u2019ve gotta say: she\u2019s worn them well.<\/em><\/p>\n<p style=\"padding-left: 30px;\"><em>So who looks best? The newbie or the old (yet ageless) pro?&#0160; Vote in our poll.<\/em><\/p>\n<p>You know what to do.<\/p>\n<p><a href=\"http:\/\/stylenews.peoplestylewatch.com\/2012\/11\/15\/kristen-stewart-cher-black-bodysuit\/%20\" target=\"_self\" rel=\"noopener\">http:\/\/stylenews.peoplestylewatch.com\/2012\/11\/15\/kristen-stewart-cher-black-bodysuit\/ <\/a><\/p>\n<p>&#0160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>People Magazine is running a bodysuit poll and who doesn&#39;t care about bodysuits so go make your voice heard: Banging bodies. Major success. Sheer jumpsuits. Three things Kristen Stewart and Cher have in common. But does K. Stew\u2019s Zuhair Murad creation live up to Cher\u2019s legendary black bodysuit? Stewart wore her revealing ensemble \u2014 a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":["post-2135","post","type-post","status-publish","format-standard","hentry","category-cher-outfit-watch","wp-image-borders","post-preview"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best? - I Found Some Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best? - I Found Some Blog\" \/>\n<meta property=\"og:description\" content=\"People Magazine is running a bodysuit poll and who doesn&#039;t care about bodysuits so go make your voice heard: Banging bodies. Major success. Sheer jumpsuits. Three things Kristen Stewart and Cher have in common. But does K. Stew\u2019s Zuhair Murad creation live up to Cher\u2019s legendary black bodysuit? Stewart wore her revealing ensemble \u2014 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/\" \/>\n<meta property=\"og:site_name\" content=\"I Found Some Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/twitter.com\/Mary_McCray\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-18T11:45:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T15:27:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg\" \/>\n<meta name=\"author\" content=\"Cher Scholar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Mary_McCray\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cher Scholar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/\"},\"author\":{\"name\":\"Cher Scholar\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/1486194d52b3026c77cf22dd16c4cb3c\"},\"headline\":\"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best?\",\"datePublished\":\"2012-11-18T11:45:06+00:00\",\"dateModified\":\"2023-02-20T15:27:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/\"},\"wordCount\":172,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\"},\"image\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg\",\"articleSection\":[\"Cher Outfit Watch\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/\",\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/\",\"name\":\"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best? - I Found Some Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg\",\"datePublished\":\"2012-11-18T11:45:06+00:00\",\"dateModified\":\"2023-02-20T15:27:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg?fit=200%2C267&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg?fit=200%2C267&ssl=1\",\"width\":200,\"height\":267},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2012\\\/11\\\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#website\",\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/\",\"name\":\"I Found Some Blog\",\"description\":\"a division of the Chersonian Institute\",\"publisher\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\",\"name\":\"Cher Scholar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"caption\":\"Cher Scholar\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/Mary_McCray\",\"https:\\\/\\\/www.pinterest.com\\\/poetmarymccray\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Mary_McCray\",\"https:\\\/\\\/marymccray.tumblr.com\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/1486194d52b3026c77cf22dd16c4cb3c\",\"name\":\"Cher Scholar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"caption\":\"Cher Scholar\"},\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/author\\\/cherscholar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best? - I Found Some Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/","og_locale":"en_US","og_type":"article","og_title":"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best? - I Found Some Blog","og_description":"People Magazine is running a bodysuit poll and who doesn&#39;t care about bodysuits so go make your voice heard: Banging bodies. Major success. Sheer jumpsuits. Three things Kristen Stewart and Cher have in common. But does K. Stew\u2019s Zuhair Murad creation live up to Cher\u2019s legendary black bodysuit? Stewart wore her revealing ensemble \u2014 a [&hellip;]","og_url":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/","og_site_name":"I Found Some Blog","article_publisher":"https:\/\/twitter.com\/Mary_McCray","article_published_time":"2012-11-18T11:45:06+00:00","article_modified_time":"2023-02-20T15:27:38+00:00","og_image":[{"url":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg","type":"","width":"","height":""}],"author":"Cher Scholar","twitter_card":"summary_large_image","twitter_site":"@Mary_McCray","twitter_misc":{"Written by":"Cher Scholar","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/#article","isPartOf":{"@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/"},"author":{"name":"Cher Scholar","@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/1486194d52b3026c77cf22dd16c4cb3c"},"headline":"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best?","datePublished":"2012-11-18T11:45:06+00:00","dateModified":"2023-02-20T15:27:38+00:00","mainEntityOfPage":{"@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/"},"wordCount":172,"commentCount":0,"publisher":{"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1"},"image":{"@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/#primaryimage"},"thumbnailUrl":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg","articleSection":["Cher Outfit Watch"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/","url":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/","name":"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best? - I Found Some Blog","isPartOf":{"@id":"https:\/\/cherscholar.com\/cherblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/#primaryimage"},"image":{"@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/#primaryimage"},"thumbnailUrl":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg","datePublished":"2012-11-18T11:45:06+00:00","dateModified":"2023-02-20T15:27:38+00:00","breadcrumb":{"@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/#primaryimage","url":"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg?fit=200%2C267&ssl=1","contentUrl":"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef017c33b32e02970b-200wi.jpg?fit=200%2C267&ssl=1","width":200,"height":267},{"@type":"BreadcrumbList","@id":"https:\/\/cherscholar.com\/cherblog\/2012\/11\/go-vote-kristen-stewart-v-cher-who-rocks-a-sheer-bodysuit-best\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cherscholar.com\/cherblog\/"},{"@type":"ListItem","position":2,"name":"Go Vote: Kristen Stewart V. Cher: Who Rocks a Sheer Bodysuit Best?"}]},{"@type":"WebSite","@id":"https:\/\/cherscholar.com\/cherblog\/#website","url":"https:\/\/cherscholar.com\/cherblog\/","name":"I Found Some Blog","description":"a division of the Chersonian Institute","publisher":{"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cherscholar.com\/cherblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1","name":"Cher Scholar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","caption":"Cher Scholar"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g"},"sameAs":["https:\/\/twitter.com\/Mary_McCray","https:\/\/www.pinterest.com\/poetmarymccray\/","https:\/\/x.com\/https:\/\/twitter.com\/Mary_McCray","https:\/\/marymccray.tumblr.com\/"]},{"@type":"Person","@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/1486194d52b3026c77cf22dd16c4cb3c","name":"Cher Scholar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","caption":"Cher Scholar"},"url":"https:\/\/cherscholar.com\/cherblog\/author\/cherscholar\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/2135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/comments?post=2135"}],"version-history":[{"count":1,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/2135\/revisions"}],"predecessor-version":[{"id":5268,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/2135\/revisions\/5268"}],"wp:attachment":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/media?parent=2135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/categories?post=2135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/tags?post=2135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}