{"id":2714,"date":"2010-09-30T15:06:14","date_gmt":"2010-09-30T21:06:14","guid":{"rendered":"https:\/\/cherscholar.com\/cherblog\/things-i-do-now-that-i-live-in-new-mexico\/"},"modified":"2023-02-20T08:35:17","modified_gmt":"2023-02-20T15:35:17","slug":"things-i-do-now-that-i-live-in-new-mexico","status":"publish","type":"post","link":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/","title":{"rendered":"Things I Do Now That I LIve in New Mexico"},"content":{"rendered":"<p>So for years my family has roasted chile peppers from New Mexico. But this year&#0160;I got to visit Chavez Farms myself to pick out my own batch. I got home and roasted them to show my hubbie what New Mexico Pepper Roasting is all about&#8230;<\/p>\n<p>Unfortunately he spent most of his time studying in the other room, except for some brief time spent posing with the peppers. That&#39;s a look that says, &quot;I&#39;m not going to help you, sweetie.&quot;<\/p>\n<p><a href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef0133f4c11bc8970b-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"display: inline;\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"IMG_3954\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef0133f4c11bc8970b\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg?w=676&#038;ssl=1\" style=\"width: 200px;\" title=\"IMG_3954\" \/><\/a>&#0160;<\/p>\n<p>The Big Jims are big but mild:<\/p>\n<p><a href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef013487e10278970c-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"display: inline;\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"IMG_3949\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef013487e10278970c\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef013487e10278970c-200wi.jpg?w=676&#038;ssl=1\" style=\"width: 200px;\" title=\"IMG_3949\" \/><\/a>&#0160;<\/p>\n<p>The Barkers are very hot:<\/p>\n<p><a href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef013487e103b1970c-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"display: inline;\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"IMG_3948\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef013487e103b1970c\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef013487e103b1970c-200wi.jpg?w=676&#038;ssl=1\" style=\"width: 200px;\" title=\"IMG_3948\" \/><\/a>&#0160;<\/p>\n<p>Some turn red real quick<br \/> (please, disregard the cheap vodka bottles in the background):<\/p>\n<p><a href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef013487e104a8970c-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"display: inline;\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"IMG_3957\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef013487e104a8970c\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef013487e104a8970c-200wi.jpg?w=676&#038;ssl=1\" style=\"width: 200px;\" title=\"IMG_3957\" \/><\/a>&#0160;<\/p>\n<p>They are broiled and then frozen and then&#0160;happily enjoyed.<\/p>\n<p><a href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef013487e105ab970c-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"float: left;\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"IMG_3953\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef013487e105ab970c\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef013487e105ab970c-200wi.jpg?w=676&#038;ssl=1\" style=\"width: 200px; margin: 0px 5px 5px 0px;\" title=\"IMG_3953\" \/><\/a> <a href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef013487e10629970c-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"float: left;\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"IMG_3961\" class=\"asset  asset-image at-xid-6a00d8341d6c7753ef013487e10629970c\" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef013487e10629970c-200wi.jpg?w=676&#038;ssl=1\" style=\"width: 200px; margin: 0px 5px 5px 0px;\" title=\"IMG_3961\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>So for years my family has roasted chile peppers from New Mexico. But this year&#0160;I got to visit Chavez Farms myself to pick out my own batch. I got home and roasted them to show my hubbie what New Mexico Pepper Roasting is all about&#8230; Unfortunately he spent most of his time studying in the [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-2714","post","type-post","status-publish","format-standard","hentry","category-what-this-really-says-about-me","wp-image-borders","post-preview"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Things I Do Now That I LIve in New Mexico - I Found Some Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Things I Do Now That I LIve in New Mexico - I Found Some Blog\" \/>\n<meta property=\"og:description\" content=\"So for years my family has roasted chile peppers from New Mexico. But this year&#160;I got to visit Chavez Farms myself to pick out my own batch. I got home and roasted them to show my hubbie what New Mexico Pepper Roasting is all about&#8230; Unfortunately he spent most of his time studying in the [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"I Found Some Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/twitter.com\/Mary_McCray\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-30T21:06:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T15:35:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg\" \/>\n<meta name=\"author\" content=\"Cher Scholar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Mary_McCray\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cher Scholar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/\"},\"author\":{\"name\":\"Cher Scholar\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/1486194d52b3026c77cf22dd16c4cb3c\"},\"headline\":\"Things I Do Now That I LIve in New Mexico\",\"datePublished\":\"2010-09-30T21:06:14+00:00\",\"dateModified\":\"2023-02-20T15:35:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/\"},\"wordCount\":130,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\"},\"image\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg\",\"articleSection\":[\"What This Really Says About Me\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/\",\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/\",\"name\":\"Things I Do Now That I LIve in New Mexico - I Found Some Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg\",\"datePublished\":\"2010-09-30T21:06:14+00:00\",\"dateModified\":\"2023-02-20T15:35:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg?fit=200%2C150&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg?fit=200%2C150&ssl=1\",\"width\":200,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2010\\\/09\\\/things-i-do-now-that-i-live-in-new-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Things I Do Now That I LIve in New Mexico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#website\",\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/\",\"name\":\"I Found Some Blog\",\"description\":\"a division of the Chersonian Institute\",\"publisher\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\",\"name\":\"Cher Scholar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"caption\":\"Cher Scholar\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/Mary_McCray\",\"https:\\\/\\\/www.pinterest.com\\\/poetmarymccray\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Mary_McCray\",\"https:\\\/\\\/marymccray.tumblr.com\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/1486194d52b3026c77cf22dd16c4cb3c\",\"name\":\"Cher Scholar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"caption\":\"Cher Scholar\"},\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/author\\\/cherscholar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Things I Do Now That I LIve in New Mexico - I Found Some Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/","og_locale":"en_US","og_type":"article","og_title":"Things I Do Now That I LIve in New Mexico - I Found Some Blog","og_description":"So for years my family has roasted chile peppers from New Mexico. But this year&#0160;I got to visit Chavez Farms myself to pick out my own batch. I got home and roasted them to show my hubbie what New Mexico Pepper Roasting is all about&#8230; Unfortunately he spent most of his time studying in the [&hellip;]","og_url":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/","og_site_name":"I Found Some Blog","article_publisher":"https:\/\/twitter.com\/Mary_McCray","article_published_time":"2010-09-30T21:06:14+00:00","article_modified_time":"2023-02-20T15:35:17+00:00","og_image":[{"url":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg","type":"","width":"","height":""}],"author":"Cher Scholar","twitter_card":"summary_large_image","twitter_site":"@Mary_McCray","twitter_misc":{"Written by":"Cher Scholar","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/#article","isPartOf":{"@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/"},"author":{"name":"Cher Scholar","@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/1486194d52b3026c77cf22dd16c4cb3c"},"headline":"Things I Do Now That I LIve in New Mexico","datePublished":"2010-09-30T21:06:14+00:00","dateModified":"2023-02-20T15:35:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/"},"wordCount":130,"commentCount":1,"publisher":{"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1"},"image":{"@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg","articleSection":["What This Really Says About Me"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/","url":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/","name":"Things I Do Now That I LIve in New Mexico - I Found Some Blog","isPartOf":{"@id":"https:\/\/cherscholar.com\/cherblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/#primaryimage"},"image":{"@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg","datePublished":"2010-09-30T21:06:14+00:00","dateModified":"2023-02-20T15:35:17+00:00","breadcrumb":{"@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/#primaryimage","url":"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg?fit=200%2C150&ssl=1","contentUrl":"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef0133f4c11bc8970b-200wi.jpg?fit=200%2C150&ssl=1","width":200,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/cherscholar.com\/cherblog\/2010\/09\/things-i-do-now-that-i-live-in-new-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cherscholar.com\/cherblog\/"},{"@type":"ListItem","position":2,"name":"Things I Do Now That I LIve in New Mexico"}]},{"@type":"WebSite","@id":"https:\/\/cherscholar.com\/cherblog\/#website","url":"https:\/\/cherscholar.com\/cherblog\/","name":"I Found Some Blog","description":"a division of the Chersonian Institute","publisher":{"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cherscholar.com\/cherblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1","name":"Cher Scholar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","caption":"Cher Scholar"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g"},"sameAs":["https:\/\/twitter.com\/Mary_McCray","https:\/\/www.pinterest.com\/poetmarymccray\/","https:\/\/x.com\/https:\/\/twitter.com\/Mary_McCray","https:\/\/marymccray.tumblr.com\/"]},{"@type":"Person","@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/1486194d52b3026c77cf22dd16c4cb3c","name":"Cher Scholar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","caption":"Cher Scholar"},"url":"https:\/\/cherscholar.com\/cherblog\/author\/cherscholar\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/2714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/comments?post=2714"}],"version-history":[{"count":1,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/2714\/revisions"}],"predecessor-version":[{"id":5552,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/2714\/revisions\/5552"}],"wp:attachment":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/media?parent=2714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/categories?post=2714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/tags?post=2714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}