{"id":3300,"date":"2008-09-05T10:17:26","date_gmt":"2008-09-05T16:17:26","guid":{"rendered":"https:\/\/cherscholar.com\/cherblog\/cher-on-the-cover-of-travel-girl\/"},"modified":"2023-02-20T08:42:27","modified_gmt":"2023-02-20T15:42:27","slug":"cher-on-the-cover-of-travel-girl","status":"publish","type":"post","link":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/","title":{"rendered":"Cher on the cover of Travel Girl"},"content":{"rendered":"<p><a href=\"http:\/\/cherscholar.typepad.com\/.a\/6a00d8341d6c7753ef00e554e5911d8833-popup\" onclick=\"window.open( this.href, &#39;_blank&#39;, &#39;width=640,height=480,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0&#39; ); return false\" style=\"FLOAT: left\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"Travel-girl_augsept\" class=\"at-xid-6a00d8341d6c7753ef00e554e5911d8833 \" src=\"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg?w=676&#038;ssl=1\" style=\"MARGIN: 0px 5px 5px 0px; WIDTH: 200px\" \/><\/a>&#160;<a href=\"http:\/\/www.travelgirlinc.com\/\">Cover with interview<\/a>: August September 2008 issue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#160;Cover with interview: August September 2008 issue.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":["post-3300","post","type-post","status-publish","format-standard","hentry","category-cher-news","wp-image-borders","post-preview"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cher on the cover of Travel Girl - I Found Some Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cher on the cover of Travel Girl - I Found Some Blog\" \/>\n<meta property=\"og:description\" content=\"&#160;Cover with interview: August September 2008 issue.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/\" \/>\n<meta property=\"og:site_name\" content=\"I Found Some Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/twitter.com\/Mary_McCray\" \/>\n<meta property=\"article:published_time\" content=\"2008-09-05T16:17:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T15:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg\" \/>\n<meta name=\"author\" content=\"Cher Scholar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Mary_McCray\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cher Scholar\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/\"},\"author\":{\"name\":\"Cher Scholar\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/1486194d52b3026c77cf22dd16c4cb3c\"},\"headline\":\"Cher on the cover of Travel Girl\",\"datePublished\":\"2008-09-05T16:17:26+00:00\",\"dateModified\":\"2023-02-20T15:42:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/\"},\"wordCount\":13,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\"},\"image\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg\",\"articleSection\":[\"Cher News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/\",\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/\",\"name\":\"Cher on the cover of Travel Girl - I Found Some Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg\",\"datePublished\":\"2008-09-05T16:17:26+00:00\",\"dateModified\":\"2023-02-20T15:42:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg?fit=200%2C258&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/cherscholar.com\\\/cherblog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg?fit=200%2C258&ssl=1\",\"width\":200,\"height\":258},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/2008\\\/09\\\/cher-on-the-cover-of-travel-girl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cher on the cover of Travel Girl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#website\",\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/\",\"name\":\"I Found Some Blog\",\"description\":\"a division of the Chersonian Institute\",\"publisher\":{\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/e4502cffa081210b71fc42907f0671c1\",\"name\":\"Cher Scholar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\",\"caption\":\"Cher Scholar\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/Mary_McCray\",\"https:\\\/\\\/www.pinterest.com\\\/poetmarymccray\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Mary_McCray\",\"https:\\\/\\\/marymccray.tumblr.com\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/#\\\/schema\\\/person\\\/1486194d52b3026c77cf22dd16c4cb3c\",\"name\":\"Cher Scholar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g\",\"caption\":\"Cher Scholar\"},\"url\":\"https:\\\/\\\/cherscholar.com\\\/cherblog\\\/author\\\/cherscholar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cher on the cover of Travel Girl - I Found Some Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/","og_locale":"en_US","og_type":"article","og_title":"Cher on the cover of Travel Girl - I Found Some Blog","og_description":"&#160;Cover with interview: August September 2008 issue.","og_url":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/","og_site_name":"I Found Some Blog","article_publisher":"https:\/\/twitter.com\/Mary_McCray","article_published_time":"2008-09-05T16:17:26+00:00","article_modified_time":"2023-02-20T15:42:27+00:00","og_image":[{"url":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg","type":"","width":"","height":""}],"author":"Cher Scholar","twitter_card":"summary_large_image","twitter_site":"@Mary_McCray","twitter_misc":{"Written by":"Cher Scholar"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/#article","isPartOf":{"@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/"},"author":{"name":"Cher Scholar","@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/1486194d52b3026c77cf22dd16c4cb3c"},"headline":"Cher on the cover of Travel Girl","datePublished":"2008-09-05T16:17:26+00:00","dateModified":"2023-02-20T15:42:27+00:00","mainEntityOfPage":{"@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/"},"wordCount":13,"commentCount":1,"publisher":{"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1"},"image":{"@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/#primaryimage"},"thumbnailUrl":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg","articleSection":["Cher News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/","url":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/","name":"Cher on the cover of Travel Girl - I Found Some Blog","isPartOf":{"@id":"https:\/\/cherscholar.com\/cherblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/#primaryimage"},"image":{"@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/#primaryimage"},"thumbnailUrl":"https:\/\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg","datePublished":"2008-09-05T16:17:26+00:00","dateModified":"2023-02-20T15:42:27+00:00","breadcrumb":{"@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/#primaryimage","url":"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg?fit=200%2C258&ssl=1","contentUrl":"https:\/\/i0.wp.com\/cherscholar.com\/cherblog\/wp-content\/uploads\/2023\/02\/6a00d8341d6c7753ef00e554e5911d8833-200wi.jpg?fit=200%2C258&ssl=1","width":200,"height":258},{"@type":"BreadcrumbList","@id":"https:\/\/cherscholar.com\/cherblog\/2008\/09\/cher-on-the-cover-of-travel-girl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cherscholar.com\/cherblog\/"},{"@type":"ListItem","position":2,"name":"Cher on the cover of Travel Girl"}]},{"@type":"WebSite","@id":"https:\/\/cherscholar.com\/cherblog\/#website","url":"https:\/\/cherscholar.com\/cherblog\/","name":"I Found Some Blog","description":"a division of the Chersonian Institute","publisher":{"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cherscholar.com\/cherblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/e4502cffa081210b71fc42907f0671c1","name":"Cher Scholar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g","caption":"Cher Scholar"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/e5e331dd4b2b6fb59b3a838e0f3b67eed388f3cc13b2bfa5a579f8660a234dca?s=96&d=mm&r=g"},"sameAs":["https:\/\/twitter.com\/Mary_McCray","https:\/\/www.pinterest.com\/poetmarymccray\/","https:\/\/x.com\/https:\/\/twitter.com\/Mary_McCray","https:\/\/marymccray.tumblr.com\/"]},{"@type":"Person","@id":"https:\/\/cherscholar.com\/cherblog\/#\/schema\/person\/1486194d52b3026c77cf22dd16c4cb3c","name":"Cher Scholar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c735f218e5b9a5311844507df1270a47467c4b027bd03c862e5b2f384aaef35f?s=96&d=mm&r=g","caption":"Cher Scholar"},"url":"https:\/\/cherscholar.com\/cherblog\/author\/cherscholar\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/3300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/comments?post=3300"}],"version-history":[{"count":1,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/3300\/revisions"}],"predecessor-version":[{"id":5150,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/posts\/3300\/revisions\/5150"}],"wp:attachment":[{"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/media?parent=3300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/categories?post=3300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cherscholar.com\/cherblog\/wp-json\/wp\/v2\/tags?post=3300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}